{"id":280,"count":1,"description":"","link":"https:\/\/www.pexgol.com\/es\/case-studies-applications\/nitrogen\/","name":"Nitrogen","slug":"nitrogen","taxonomy":"case-studies-applications","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nitrogen Archives - Pexgol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pexgol.com\/es\/case-studies-applications\/nitrogen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nitrogen Archives - Pexgol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pexgol.com\/es\/case-studies-applications\/nitrogen\/\" \/>\n<meta property=\"og:site_name\" content=\"Pexgol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/case-studies-applications\\\/nitrogen\\\/\",\"url\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/case-studies-applications\\\/nitrogen\\\/\",\"name\":\"Nitrogen Archives - Pexgol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/case-studies-applications\\\/nitrogen\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/case-studies-applications\\\/nitrogen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nitrogen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/\",\"name\":\"Pexgol\",\"description\":\"Pexgol is a global leader of heavy duty PE-Xa pipe material. Pexgol products are chemically unbreakable cross-connection between polyethylene chains.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/#organization\",\"name\":\"Pexgol\",\"url\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pexgol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-pexgol-white.svg\",\"contentUrl\":\"https:\\\/\\\/www.pexgol.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-pexgol-white.svg\",\"width\":827,\"height\":329.2,\"caption\":\"Pexgol\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pexgol.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nitrogen Archives - Pexgol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pexgol.com\/es\/case-studies-applications\/nitrogen\/","og_locale":"es_ES","og_type":"article","og_title":"Nitrogen Archives - Pexgol","og_url":"https:\/\/www.pexgol.com\/es\/case-studies-applications\/nitrogen\/","og_site_name":"Pexgol","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.pexgol.com\/es\/case-studies-applications\/nitrogen\/","url":"https:\/\/www.pexgol.com\/es\/case-studies-applications\/nitrogen\/","name":"Nitrogen Archives - Pexgol","isPartOf":{"@id":"https:\/\/www.pexgol.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.pexgol.com\/es\/case-studies-applications\/nitrogen\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pexgol.com\/es\/case-studies-applications\/nitrogen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pexgol.com\/es\/"},{"@type":"ListItem","position":2,"name":"Nitrogen"}]},{"@type":"WebSite","@id":"https:\/\/www.pexgol.com\/es\/#website","url":"https:\/\/www.pexgol.com\/es\/","name":"Pexgol","description":"Pexgol is a global leader of heavy duty PE-Xa pipe material. Pexgol products are chemically unbreakable cross-connection between polyethylene chains.","publisher":{"@id":"https:\/\/www.pexgol.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pexgol.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.pexgol.com\/es\/#organization","name":"Pexgol","url":"https:\/\/www.pexgol.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pexgol.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.pexgol.com\/wp-content\/uploads\/2020\/02\/logo-pexgol-white.svg","contentUrl":"https:\/\/www.pexgol.com\/wp-content\/uploads\/2020\/02\/logo-pexgol-white.svg","width":827,"height":329.2,"caption":"Pexgol"},"image":{"@id":"https:\/\/www.pexgol.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.pexgol.com\/es\/wp-json\/wp\/v2\/case-studies-applications\/280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pexgol.com\/es\/wp-json\/wp\/v2\/case-studies-applications"}],"about":[{"href":"https:\/\/www.pexgol.com\/es\/wp-json\/wp\/v2\/taxonomies\/case-studies-applications"}],"wp:post_type":[{"href":"https:\/\/www.pexgol.com\/es\/wp-json\/wp\/v2\/case-studies?case-studies-applications=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}